{"id":884,"count":4,"description":"","link":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot\/172","name":"172","slug":"172","taxonomy":"product_cat","parent":597,"meta":[],"menu_order":0,"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot\/172\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/884#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/retrocrea.fr\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/store#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/store#listItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/store\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques#listItem\",\"name\":\"Marques\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques#listItem\",\"position\":3,\"name\":\"Marques\",\"item\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques\\\/peugeot#listItem\",\"name\":\"Peugeot\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/store#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques\\\/peugeot#listItem\",\"position\":4,\"name\":\"Peugeot\",\"item\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques\\\/peugeot\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques\\\/peugeot\\\/172#listItem\",\"name\":\"172\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques#listItem\",\"name\":\"Marques\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques\\\/peugeot\\\/172#listItem\",\"position\":5,\"name\":\"172\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/product-category\\\/marques\\\/peugeot#listItem\",\"name\":\"Peugeot\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/884#collectionpage\",\"url\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/884\",\"name\":\"172 - RetroCrea.fr - Pi\\u00e8ces pour v\\u00e9hicules de collection\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/884#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/#organization\",\"name\":\"RetroCrea.fr - Vente en ligne et refabrication sur-mesure de pi\\u00e8ces pour v\\u00e9hicules anciens\",\"description\":\"Votre fournisseur de pi\\u00e8ces d\\u00e9tach\\u00e9es, accessoires et documentations pour v\\u00e9hicules de collection des ann\\u00e9es 1920 \\u00e0 1980\",\"url\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/retrocrea.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-RetroCrea-logo-quadri-icon.png\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/884\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/884\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/\",\"name\":\"RetroCrea.fr - Vente en ligne et refabrication sur-mesure de pi\\u00e8ces pour v\\u00e9hicules anciens\",\"alternateName\":\"RetroCrea.fr\",\"description\":\"Votre fournisseur de pi\\u00e8ces d\\u00e9tach\\u00e9es, accessoires et documentations pour v\\u00e9hicules de collection des ann\\u00e9es 1920 \\u00e0 1980\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/retrocrea.fr\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"172 - RetroCrea.fr - Pi\u00e8ces pour v\u00e9hicules de collection","description":"","canonical_url":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot\/172","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/884#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en#listItem","position":1,"name":"Accueil","item":"https:\/\/retrocrea.fr\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/store#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/store#listItem","position":2,"name":"Boutique","item":"https:\/\/retrocrea.fr\/en\/store","nextItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques#listItem","name":"Marques"},"previousItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques#listItem","position":3,"name":"Marques","item":"https:\/\/retrocrea.fr\/en\/product-category\/marques","nextItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot#listItem","name":"Peugeot"},"previousItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/store#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot#listItem","position":4,"name":"Peugeot","item":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot","nextItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot\/172#listItem","name":"172"},"previousItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques#listItem","name":"Marques"}},{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot\/172#listItem","position":5,"name":"172","previousItem":{"@type":"ListItem","@id":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot#listItem","name":"Peugeot"}}]},{"@type":"CollectionPage","@id":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/884#collectionpage","url":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/884","name":"172 - RetroCrea.fr - Pi\u00e8ces pour v\u00e9hicules de collection","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/retrocrea.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/884#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/retrocrea.fr\/en\/#organization","name":"RetroCrea.fr - Vente en ligne et refabrication sur-mesure de pi\u00e8ces pour v\u00e9hicules anciens","description":"Votre fournisseur de pi\u00e8ces d\u00e9tach\u00e9es, accessoires et documentations pour v\u00e9hicules de collection des ann\u00e9es 1920 \u00e0 1980","url":"https:\/\/retrocrea.fr\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/retrocrea.fr\/wp-content\/uploads\/2024\/05\/cropped-RetroCrea-logo-quadri-icon.png","@id":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/884\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/884\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/retrocrea.fr\/en\/#website","url":"https:\/\/retrocrea.fr\/en\/","name":"RetroCrea.fr - Vente en ligne et refabrication sur-mesure de pi\u00e8ces pour v\u00e9hicules anciens","alternateName":"RetroCrea.fr","description":"Votre fournisseur de pi\u00e8ces d\u00e9tach\u00e9es, accessoires et documentations pour v\u00e9hicules de collection des ann\u00e9es 1920 \u00e0 1980","inLanguage":"en-GB","publisher":{"@id":"https:\/\/retrocrea.fr\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/retrocrea.fr\/en\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/retrocrea.fr\/en\/store\" title=\"Boutique\">Boutique<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/retrocrea.fr\/en\/product-category\/marques\" title=\"Marques\">Marques<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot\" title=\"Peugeot\">Peugeot<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t172\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/retrocrea.fr\/en"},{"label":"Boutique","link":"https:\/\/retrocrea.fr\/en\/store"},{"label":"Marques","link":"https:\/\/retrocrea.fr\/en\/product-category\/marques"},{"label":"Peugeot","link":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot"},{"label":"172","link":"https:\/\/retrocrea.fr\/en\/product-category\/marques\/peugeot\/172"}],"_links":{"self":[{"href":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product_cat\/597"}],"wp:post_type":[{"href":"https:\/\/retrocrea.fr\/en\/wp-json\/wp\/v2\/product?product_cat=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}